{"id":153,"date":"2017-06-15T07:04:05","date_gmt":"2017-06-15T07:04:05","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart\/?post_type=portfolio&#038;p=153"},"modified":"2025-03-22T02:02:36","modified_gmt":"2025-03-21T23:02:36","slug":"a-lacus-bibendum-pulvinar","status":"publish","type":"portfolio","link":"https:\/\/nextfert.com.tr\/en\/portfolio\/a-lacus-bibendum-pulvinar\/","title":{"rendered":"A lacus bibendum pulvinar"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1626936454131 vc_row-o-equal-height vc_row-o-content-top vc_row-flex wd-rs-60f9147ead3f3\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-12 wd-rs-60f91324ddffd\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"gallery_975\" class=\"wd-images-gallery wd-wpb photoswipe-images\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\n\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:1;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-9.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-9.jpg\" class=\"wd-gallery-image image-1\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-9.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-9-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-9-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-9-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8.jpg\" class=\"wd-gallery-image image-2\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6.jpg\" class=\"wd-gallery-image image-3\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"4\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5.jpg\" class=\"wd-gallery-image image-4\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-4.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"5\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-4.jpg\" class=\"wd-gallery-image image-5\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-4.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-4-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-4-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-4-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"6\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3.jpg\" class=\"wd-gallery-image image-6\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"wd-6a97bf3e7159a\" class=\"wd-image wd-wpb text-left  photoswipe-images\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1.jpg\"  data-width=\"800\" data-height=\"800\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-12 woodmart-sticky-column wd_sticky_offset_150 wd-rs-60f9141632294\"><div class=\"vc_column-inner vc_custom_1626936354898\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1494415923456 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1494415839649\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-60f90f4a92d4c\" class=\"title-wrapper wd-wpb set-mb-s reset-last-child  wd-rs-60f90f4a92d4c wd-title-color-default wd-title-style-default text-left vc_custom_1626935118715 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xxl\" >Our Latest Work<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-60f90f7f0ecc3\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f90f7f0ecc3 text-left wd-font-weight-400 wd-fontsize-s font-primary vc_custom_1626935170467\">\n\t\t\t<p>we are creative agency<\/p>\n\t\t<\/div>\n\t\t\t\t<div id=\"wd-60f90fc934f5f\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f90fc934f5f text-left\">\n\t\t\t<p>Accum luctus dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod tincidunt ut laoreet dolore magna aliquam erat volutpat. Ut wisi enim ad minim veniam, quis nostrud exerci tation.<\/p>\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1499149309417\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-60f910e87b33c\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f910e87b33c text-left wd-font-weight-600 color-title wd-fontsize-custom font-primary vc_custom_1626935532187\">\n\t\t\t<p>CLIENT<\/p>\n\t\t<\/div>\n\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_custom_1481478904779\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-60f9114a6058f\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f9114a6058f text-left wd-fontsize-custom vc_custom_1626935637938\">\n\t\t\t<p>MINDSPARKLE SHOP<\/p>\n\t\t<\/div>\n\t\t\t\t<div id=\"wd-60f910fdd71d8\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f910fdd71d8 text-left wd-font-weight-600 color-title wd-fontsize-custom font-primary vc_custom_1626935552113\">\n\t\t\t<p>DESIGNER<\/p>\n\t\t<\/div>\n\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_custom_1481478904779\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-60f911747b4de\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f911747b4de text-left wd-fontsize-custom vc_custom_1626935671195\">\n\t\t\t<p>JOHN DOE<\/p>\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1499149316069\"><div class=\"wpb_wrapper\">\t\t<div id=\"wd-60f9111e21318\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f9111e21318 text-left wd-font-weight-600 color-title wd-fontsize-custom font-primary vc_custom_1626935584442\">\n\t\t\t<p>MATERIALS<\/p>\n\t\t<\/div>\n\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_custom_1481478904779\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-60f9118f75eab\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f9118f75eab text-left wd-fontsize-custom vc_custom_1626935697610\">\n\t\t\t<p>WOOD, PAPER<\/p>\n\t\t<\/div>\n\t\t\t\t<div id=\"wd-60f9112b25516\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f9112b25516 text-left wd-font-weight-600 color-title wd-fontsize-custom font-primary vc_custom_1626935597041\">\n\t\t\t<p>WEBSITE<\/p>\n\t\t<\/div>\n\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_custom_1481478904779\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-60f911814813e\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f911814813e text-left wd-fontsize-custom vc_custom_1626935683217\">\n\t\t\t<p>XTEMOS.COM\/WOOD<\/p>\n\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1626936460958 wd-rs-60f9148950124\"><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-60f9150336742\" class=\"wd-rs-60f9150336742 wd-info-box wd-wpb text-center box-icon-align-top box-style- color-scheme- wd-bg-none vc_custom_1626936586392\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-text text-size-large box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t01.\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-s\"><strong>VULPUTATE A PORTA<\/strong><\/h4>\t\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"><p>Vestibulum nam lobortis scelerisque eu mi leo orci placerat a parturient congue non commodo felis in dui<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-60f9150c8f1ce\" class=\"wd-rs-60f9150c8f1ce wd-info-box wd-wpb text-center box-icon-align-top box-style- color-scheme- wd-bg-none vc_custom_1626936598575\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-text text-size-large box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t02.\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-s\"><strong>SUSCIPIT HABITANT<\/strong><\/h4>\t\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"><p>Ullamcorper adipiscing vel hac a egestas leo in sit pharetra auctor nibh mauris mi cum curae\u00a0nec nasceturam<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t<div id=\"wd-60f91518c7a64\" class=\"wd-rs-60f91518c7a64 wd-info-box wd-wpb text-center box-icon-align-top box-style- color-scheme- wd-bg-none vc_custom_1626936609700\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-text text-size-large box-icon-simple\">\n\t\t\t\t\t\t\t<div class=\"info-box-icon\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t03.\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<h4 class=\"info-box-title title box-title-style-default wd-fontsize-s\"><strong>VESTIBULUM CUBILIA<\/strong><\/h4>\t\t\t\t\t\t<div class=\"info-box-inner set-cont-mb-s reset-last-child\"><p>Gravida morbi platea at arcu convallis a id id suspendisse parturient adipiscing vestibulum. Praesent interdu.<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1626936222033 vc_row-o-equal-height vc_row-o-content-top vc_row-flex wd-rs-60f9138122944\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-12 woodmart-sticky-column wd_sticky_offset_150 wd-rs-60f914455acf6\"><div class=\"vc_column-inner vc_custom_1626936396882\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1494418291071 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner vc_custom_1494415839649\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-60f91240994ab\" class=\"title-wrapper wd-wpb set-mb-s reset-last-child  wd-rs-60f91240994ab wd-title-color-default wd-title-style-default text-left vc_custom_1626935875363 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >Purus lectus scelerisque <em>parturient<\/em> lobortis namar<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_custom_1494420107842\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#eaeaea;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\t\t<div id=\"wd-60f911fce8a70\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-60f911fce8a70 text-left vc_custom_1626935814104\">\n\t\t\t<p>Purus <strong><a href=\"#\">vel sapien<\/a><\/strong> a mollis fusce parturient a laoreet vestibulum purus ullamcorper tellus ante at duira convallis ac vel a vestibulum sem ridiculus sapien.<\/p>\n<ul class=\"unordered-list\">\n<li>Suscipit habitant vulputate a porta.<\/li>\n<li>Consectetur vestibulum cubilia acc.<\/li>\n<li>Scelerisque litora ipsum parturient.<\/li>\n<\/ul>\n<p>Id volutpat consequat <strong><a href=\"#\">arcu tristique<\/a><\/strong> praesent sed sapien a a sagittis sit condimentum hac ut congue.<\/p>\n\t\t<\/div>\n\t\t<div id=\"wd-6a97bf3e764a2\" class=\"wd-button-wrapper text-center inline-element\"><a href=\"#\" title=\"\" class=\"btn btn-color-black btn-style-default btn-style-rectangle btn-size-default\">VIEW MORE<\/a><\/div><div id=\"wd-6a97bf3e76511\" class=\"wd-button-wrapper text-center inline-element\"><a href=\"#\" title=\"\" class=\"btn btn-color-default btn-style-bordered btn-style-rectangle btn-size-default\">CONTACT US<\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-12 wd-rs-60f913a6d621a\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"gallery_692\" class=\"wd-images-gallery wd-wpb photoswipe-images\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\n\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:2;--wd-col-md:2;--wd-col-sm:1;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-7.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-7.jpg\" class=\"wd-gallery-image image-1\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-7.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-7-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-7-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-7-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5.jpg\" class=\"wd-gallery-image image-2\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-5-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6.jpg\" class=\"wd-gallery-image image-3\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-6-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"4\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8.jpg\" class=\"wd-gallery-image image-4\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-8-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"5\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1.jpg\" class=\"wd-gallery-image image-5\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-1-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-2.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"6\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-2.jpg\" class=\"wd-gallery-image image-6\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-2.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-2-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-2-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-2-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<div id=\"wd-6a97bf3e77c56\" class=\"wd-image wd-wpb text-left  photoswipe-images\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3.jpg\"  data-width=\"800\" data-height=\"800\">\n\t\t\t\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3.jpg 800w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3-430x430.jpg 430w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3-150x150.jpg 150w, https:\/\/nextfert.com.tr\/wp-content\/uploads\/2017\/06\/portfolio-3-700x700.jpg 700w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Our Latest Work we are creative agency Accum luctus dolor sit amet, consectetuer adipiscing elit, sed diam nonummy nibh euismod","protected":false},"featured_media":959,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[32],"class_list":["post-153","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","project-cat-furniture"],"_links":{"self":[{"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/portfolio\/153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/comments?post=153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/media\/959"}],"wp:attachment":[{"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/media?parent=153"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/nextfert.com.tr\/en\/wp-json\/wp\/v2\/project-cat?post=153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}